{"id":10869,"date":"2020-08-20T11:00:04","date_gmt":"2020-08-20T14:00:04","guid":{"rendered":"https:\/\/iyengarbrasil.com\/?p=10869"},"modified":"2020-08-20T11:00:04","modified_gmt":"2020-08-20T14:00:04","slug":"savasana-e-o-tempo","status":"publish","type":"post","link":"https:\/\/iyengarbrasil.com\/en\/blog\/savasana-e-o-tempo\/","title":{"rendered":"Savasana e o tempo"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">6\u00ba Punyatithi Guruji BKS Iyengar<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Punyatithi \u00e9 o dia sagrado que se celebra a morte de uma pessoa. No dia 20 de Agosto de 2014, Guruji Iyengar fez a sua passagem. Somos eternamente gratos pelos seus ensinamentos, que se mant\u00e9m t\u00e3o vivos no presente.<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p><strong><i>Por B.K.S. Iyengar\u00a0<\/i><\/strong><\/p>\n<p><em><span style=\"font-weight: 400;\">Trecho do livro Luz na Vida<\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Muitos querem saber por que, no meu livro <\/span><i><span style=\"font-weight: 400;\">A luz sobre o Yoga<\/span><\/i><span style=\"font-weight: 400;\">, refiro-me ao <\/span><i><span style=\"font-weight: 400;\">Savasana <\/span><\/i><span style=\"font-weight: 400;\">(postura do cad\u00e1ver) como a posi\u00e7\u00e3o mais dif\u00edcil. Para a maioria das pessoas, a postura do cad\u00e1ver \u00e9 uma recompensa agrad\u00e1vel depois de uma aula de ioga cansativa, em que experimentam um relaxamento t\u00f3rpido ou vibrante e, em certa medida, luminoso. Luminoso aqui significa <\/span><i><span style=\"font-weight: 400;\">satvico<\/span><\/i><span style=\"font-weight: 400;\">, ou seja, consciente e passivo. T\u00f3rpido significa <\/span><i><span style=\"font-weight: 400;\">tam\u00e1sico<\/span><\/i><span style=\"font-weight: 400;\">, e, como muitos alunos chegam \u00e0 aula depois de um dia duro de trabalho, nunca me opus a isso. \u00c9 natural que aconte\u00e7a, e muitas vezes os roncos comp\u00f5em a m\u00fasica que encerra uma aula repleta de alunos \u2013 entre eles os j\u00e1 veteranos. Pode ser que eu seja muito exigente nas posturas em p\u00e9, mas creio que jamais acordei um aluno durante o <\/span><i><span style=\"font-weight: 400;\">Savasana<\/span><\/i><span style=\"font-weight: 400;\">, exceto talvez na hora de mand\u00e1-lo para casa. Mas o prop\u00f3sito do <\/span><i><span style=\"font-weight: 400;\">Savasana<\/span><\/i><span style=\"font-weight: 400;\"> n\u00e3o \u00e9 fazer adormecer. Se fosse assim, n\u00e3o seria uma posi\u00e7\u00e3o dif\u00edcil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O objetivo do <\/span><i><span style=\"font-weight: 400;\">Savasana <\/span><\/i><span style=\"font-weight: 400;\">\u00e9 fazer soltar, do mesmo modo que, como mencionei h\u00e1 pouco, uma cobra solta sua pele para ressurgir lustrosa e fulgurante em suas cores novas. Temos multa peles, camadas, pensamentos, preconceitos, id\u00e9ias preconcebidas, mem\u00f3rias e projetos para o futuro. O <\/span><i><span style=\"font-weight: 400;\">Savasana <\/span><\/i><span style=\"font-weight: 400;\">consiste soltar todas essas peles para que possamos ver como \u00e9 magn\u00edfica e lustrosa, serena e consciente a bela serpente irisada reside dentro de n\u00f3s. E, a exemplo da serpente, nos deitamos no ch\u00e3o, deixando a superf\u00edcie do corpo o m\u00e1ximo poss\u00edvel em contato com ele.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ora, se o <\/span><i><span style=\"font-weight: 400;\">Savasana <\/span><\/i><span style=\"font-weight: 400;\">tem que ver com relaxamento, o que nos impede de relaxar? A tens\u00e3o. A tens\u00e3o resulta de estarmos agarrados a vida e, assim, sob o controle dos milhares de fios invis\u00edveis que nos prendem ao mundo conhecido, ao &#8220;eu&#8221; conhecido, ao ambiente conhecido em que ele atua. S\u00e3o os fios que ligam o &#8220;eu&#8221; ao seu ambiente que nos proporcionam o senso de identidade. Meus alunos, quando se deitam no ch\u00e3o ao t\u00e9rmino de uma aula puxada, ainda est\u00e3o identificados com seu papel de marido ou esposa, ainda preocupados com as compras que ter\u00e3o de fazer a caminho de casa, com os pais que est\u00e3o \u00e0 sua espera, com os filhos que precisam de ajuda com a li\u00e7\u00e3o de casa. Eles ficam cansados porque mant\u00eam a consci\u00eancia de que s\u00e3o executivos que tiveram um dia extenuante no trabalho. Talvez o dia tenha transcorrido bem; talvez n\u00e3o. Meus alunos s\u00e3o todos filhos, filhas, maridos, esposas, trabalhadores, pais, homens ou mulheres. Os milhares de fios da identidade os amarram ao solo quando se deitam em <\/span><i><span style=\"font-weight: 400;\">Savasana<\/span><\/i><span style=\"font-weight: 400;\">, como Gulliver aprisionado pelos fios dos min\u00fasculos liliputianos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O <\/span><i><span style=\"font-weight: 400;\">Savasana <\/span><\/i><span style=\"font-weight: 400;\">utiliza t\u00e9cnicas de relaxamento para cortar esses fios. O resultado disso n\u00e3o \u00e9, como na medita\u00e7\u00e3o, a liberdade, mas a perda da identidade. N\u00e3o digo perda da falsa identidade porque, no mundo em que operam, essas identidades s\u00e3o reais. No entanto, de um ponto de vista mais amplo, elas s\u00e3o irreais. Mesmo o fato de ser homem ou mulher \u00e9 uma identidade que pode ser derrubada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Relaxar \u00e9 interromper a tens\u00e3o. Interromper a tens\u00e3o \u00e9 cortar os fios que nos prendem \u00e0 identidade. Perder a identidade \u00e9 descobrir quem n\u00e3o somos. N\u00e3o disse antes que a intelig\u00eancia \u00e9 o bisturi que extirpa o que \u00e9 irreal para deixar somente a verdade? N\u00e3o \u00e9 verdade que, quando est\u00e1 deitado em Savasana, numa posi\u00e7\u00e3o harmoniosa e equilibrada, voc\u00ea se sente presente e sem forma? Quando se sente presente e sem forma, n\u00e3o sente a aus\u00eancia de uma identidade espec\u00edfica? Voc\u00ea est\u00e1 ali, mas quem est\u00e1 ali? Ningu\u00e9m. S\u00f3 a percep\u00e7\u00e3o presente, sem movimento nem tempo, est\u00e1 ali. A percep\u00e7\u00e3o presente \u00e9 a extin\u00e7\u00e3o do tempo na consci\u00eancia humana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esse \u00e9 o problema com o tempo. S\u00f3 podemos conceb\u00ea-lo em rela\u00e7\u00e3o ao espa\u00e7o, como um rio fluindo ou um peda\u00e7o de cord\u00e3o. Dividimos o cord\u00e3o em d\u00e9cadas, anos, meses, dias, horas, minutos e segundos. Essas s\u00e3o as extens\u00f5es do tempo, e, seja o tempo o que for, n\u00e3o \u00e9 justo nem correto trat\u00e1-lo como uma dimens\u00e3o do espa\u00e7o, algo a ser medido por um comprimento, como uma parede ou uma estante. Outro problema \u00e9 que consideramos o tempo algo vazio, destitu\u00eddo de significado, como um balde sem nada, at\u00e9 que o enchamos com alguma coisa \u2013 nossas atividades, por exemplo. Seja o tempo o que for, devemos compreend\u00ea-lo plenamente em sua ess\u00eancia, em sua natureza, como a flor que cresce no deserto sem precisar de nenhum observador para realizar o potencial da pr\u00f3pria beleza. Se voc\u00ea tentar imaginar o tempo sem usar conceitos espaciais, perceber\u00e1 que \u00e9 extremamente dif\u00edcil. Por isso digo que n\u00e3o integramos ainda o tempo a nossa consci\u00eancia, como fizemos com as tr\u00eas dimens\u00f5es do espa\u00e7o. O poder da ci\u00eancia \u00e9 a prova de nossa capacidade de nos projetar no espa\u00e7o. Mas espa\u00e7o sem tempo \u00e9 como m\u00fasculo sem c\u00e9rebro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para n\u00f3s, o tempo parece mover-se, fluir, ter dura\u00e7\u00e3o, extens\u00e3o \u2013 portanto, ser espacial. Em outras palavras, estamos presos no aparente movimento do tempo. Contudo, todos os caminhos espirituais falam da import\u00e2ncia primordial de viver no presente. O que \u00e9 o momento presente? Um segundo? Ou algo menor? Pela l\u00f3gica, o presente s\u00f3 pode ser uma unidade de tempo infinitamente pequena, um segundo dividido pelo infinito. Isso n\u00e3o existe. Como extens\u00e3o de tempo, o presente simplesmente n\u00e3o existe. De que forma, ent\u00e3o, viver no presente? \u00c9 um paradoxo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Temos de encontrar o presente por outros meios. A \u00fanica maneira de fazer isso \u00e9 dissoci\u00e1-lo do passado e do futuro. Desse modo, o tempo n\u00e3o pode fluir. Ele literalmente p\u00e1ra, como acontece na medita\u00e7\u00e3o e no Samadhi. O <\/span><i><span style=\"font-weight: 400;\">Savasana <\/span><\/i><span style=\"font-weight: 400;\">\u00e9 a chave para entender isso. Nossa identidade e afilia\u00e7\u00e3o nos ligam ao passado e ao futuro. Nada na vida nos liga ao presente, exceto o estado de ser. A a\u00e7\u00e3o acontece no decorrer do tempo; ela tem dura\u00e7\u00e3o. Ser transcende o tempo. O estado de ser s\u00f3 \u00e9 alcan\u00e7ado quando s\u00e3o cortados todos os fios que ligam ao passado ou ao futuro. Nasci homem; serei homem amanh\u00e3. Posso agora, no Savasana, deixar de lado a identidade sexual que me liga ao passado e ao futuro? Posso existir numa percep\u00e7\u00e3o de tempo distinta, na qual passado e futuro n\u00e3o se imp\u00f5em ao presente nem o maculam? Savasana \u00e9 ser sem ter sido, ser sem vir a ser. E ser sem ningu\u00e9m que \u00e9. N\u00e3o surpreende que seja o asana mais dif\u00edcil, a porta para a medita\u00e7\u00e3o n\u00e3o dualista e para a fus\u00e3o c\u00f3smica do samadhi.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>6\u00ba Punyatithi Guruji BKS Iyengar Punyatithi \u00e9 o dia sagrado que se celebra a morte de uma pessoa. No dia 20 de Agosto de 2014, Guruji Iyengar fez a sua passagem. Somos eternamente gratos pelos seus ensinamentos, que se mant\u00e9m t\u00e3o vivos no presente. &nbsp; Por B.K.S. Iyengar\u00a0 Trecho do livro Luz na Vida Muitos [&hellip;]<\/p>\n","protected":false},"author":122,"featured_media":10874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[],"tags":[],"class_list":["post-10869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","entry","has-media"],"acf":{"photo_gallery":{"top_slider_images":[[{"id":10872,"title":"gurujisavasana2","caption":"","full_image_url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2.jpg","thumbnail_image_url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-150x150.jpg","large_srcset":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-1024x698.jpg 1024w, https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-220x150.jpg 220w, https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-768x524.jpg 768w, https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2.jpg 1195w","medium_srcset":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-220x150.jpg 220w, https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-1024x698.jpg 1024w, https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-768x524.jpg 768w, https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2.jpg 1195w","media_details":{"width":1195,"height":815,"sizes":{"medium":{"file":"gurujisavasana2-220x150.jpg","width":220,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-220x150.jpg"},"large":{"file":"gurujisavasana2-1024x698.jpg","width":1024,"height":698,"mime-type":"image\/jpeg","source_url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-1024x698.jpg"},"thumbnail":{"file":"gurujisavasana2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-150x150.jpg"},"medium_large":{"file":"gurujisavasana2-768x524.jpg","width":768,"height":524,"mime-type":"image\/jpeg","source_url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana2-768x524.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Savasana e o tempo - Iyengar Brasil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iyengarbrasil.com\/en\/blog\/savasana-e-o-tempo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Savasana e o tempo - Iyengar Brasil\" \/>\n<meta property=\"og:description\" content=\"6\u00ba Punyatithi Guruji BKS Iyengar Punyatithi \u00e9 o dia sagrado que se celebra a morte de uma pessoa. No dia 20 de Agosto de 2014, Guruji Iyengar fez a sua passagem. Somos eternamente gratos pelos seus ensinamentos, que se mant\u00e9m t\u00e3o vivos no presente. &nbsp; Por B.K.S. Iyengar\u00a0 Trecho do livro Luz na Vida Muitos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iyengarbrasil.com\/en\/blog\/savasana-e-o-tempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Iyengar Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-20T14:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maur\u00edcio Frighetto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maur\u00edcio Frighetto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/\"},\"author\":{\"name\":\"Maur\u00edcio Frighetto\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#\\\/schema\\\/person\\\/28c396a9ddf6f57027a58358233673a9\"},\"headline\":\"Savasana e o tempo\",\"datePublished\":\"2020-08-20T14:00:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/\"},\"wordCount\":1224,\"publisher\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iyengarbrasil.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/gurujisavasana.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/\",\"url\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/\",\"name\":\"Savasana e o tempo - Iyengar Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iyengarbrasil.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/gurujisavasana.jpg\",\"datePublished\":\"2020-08-20T14:00:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iyengarbrasil.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/gurujisavasana.jpg\",\"contentUrl\":\"https:\\\/\\\/iyengarbrasil.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/gurujisavasana.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/blog\\\/savasana-e-o-tempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/iyengarbrasil.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Savasana e o tempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#website\",\"url\":\"https:\\\/\\\/iyengarbrasil.com\\\/\",\"name\":\"Iyengar Brasil\",\"description\":\"Centro Iyengar Yoga Florian\u00f3polis \\\/ Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iyengarbrasil.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#organization\",\"name\":\"Iyengar Brasil\",\"url\":\"https:\\\/\\\/iyengarbrasil.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iyengarbrasil.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/iyengarbrasil.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo@2x.png\",\"width\":401,\"height\":401,\"caption\":\"Iyengar Brasil\"},\"image\":{\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iyengarbrasil.com\\\/#\\\/schema\\\/person\\\/28c396a9ddf6f57027a58358233673a9\",\"name\":\"Maur\u00edcio Frighetto\",\"url\":\"https:\\\/\\\/iyengarbrasil.com\\\/en\\\/author\\\/mauricio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Savasana e o tempo - Iyengar Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iyengarbrasil.com\/en\/blog\/savasana-e-o-tempo\/","og_locale":"en_US","og_type":"article","og_title":"Savasana e o tempo - Iyengar Brasil","og_description":"6\u00ba Punyatithi Guruji BKS Iyengar Punyatithi \u00e9 o dia sagrado que se celebra a morte de uma pessoa. No dia 20 de Agosto de 2014, Guruji Iyengar fez a sua passagem. Somos eternamente gratos pelos seus ensinamentos, que se mant\u00e9m t\u00e3o vivos no presente. &nbsp; Por B.K.S. Iyengar\u00a0 Trecho do livro Luz na Vida Muitos [&hellip;]","og_url":"https:\/\/iyengarbrasil.com\/en\/blog\/savasana-e-o-tempo\/","og_site_name":"Iyengar Brasil","article_published_time":"2020-08-20T14:00:04+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana.jpg","type":"image\/jpeg"}],"author":"Maur\u00edcio Frighetto","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maur\u00edcio Frighetto","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#article","isPartOf":{"@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/"},"author":{"name":"Maur\u00edcio Frighetto","@id":"https:\/\/iyengarbrasil.com\/#\/schema\/person\/28c396a9ddf6f57027a58358233673a9"},"headline":"Savasana e o tempo","datePublished":"2020-08-20T14:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/"},"wordCount":1224,"publisher":{"@id":"https:\/\/iyengarbrasil.com\/#organization"},"image":{"@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/","url":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/","name":"Savasana e o tempo - Iyengar Brasil","isPartOf":{"@id":"https:\/\/iyengarbrasil.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#primaryimage"},"image":{"@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana.jpg","datePublished":"2020-08-20T14:00:04+00:00","breadcrumb":{"@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#primaryimage","url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana.jpg","contentUrl":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2020\/08\/gurujisavasana.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/iyengarbrasil.com\/blog\/savasana-e-o-tempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/iyengarbrasil.com\/"},{"@type":"ListItem","position":2,"name":"Savasana e o tempo"}]},{"@type":"WebSite","@id":"https:\/\/iyengarbrasil.com\/#website","url":"https:\/\/iyengarbrasil.com\/","name":"Iyengar Brasil","description":"Centro Iyengar Yoga Florian\u00f3polis \/ Brasil","publisher":{"@id":"https:\/\/iyengarbrasil.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iyengarbrasil.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/iyengarbrasil.com\/#organization","name":"Iyengar Brasil","url":"https:\/\/iyengarbrasil.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iyengarbrasil.com\/#\/schema\/logo\/image\/","url":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2022\/06\/cropped-logo@2x.png","contentUrl":"https:\/\/iyengarbrasil.com\/wp-content\/uploads\/2022\/06\/cropped-logo@2x.png","width":401,"height":401,"caption":"Iyengar Brasil"},"image":{"@id":"https:\/\/iyengarbrasil.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/iyengarbrasil.com\/#\/schema\/person\/28c396a9ddf6f57027a58358233673a9","name":"Maur\u00edcio Frighetto","url":"https:\/\/iyengarbrasil.com\/en\/author\/mauricio\/"}]}},"_links":{"self":[{"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/posts\/10869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/comments?post=10869"}],"version-history":[{"count":6,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/posts\/10869\/revisions"}],"predecessor-version":[{"id":10878,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/posts\/10869\/revisions\/10878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/media\/10874"}],"wp:attachment":[{"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/media?parent=10869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/categories?post=10869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iyengarbrasil.com\/en\/wp-json\/wp\/v2\/tags?post=10869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}